{"id":6277,"date":"2022-06-17T07:45:59","date_gmt":"2022-06-17T07:45:59","guid":{"rendered":"https:\/\/fundacionporlajusticia.accesia.info\/?p=6277"},"modified":"2022-06-17T08:04:26","modified_gmt":"2022-06-17T08:04:26","slug":"firma-convenio-fxj-sjm","status":"publish","type":"post","link":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/","title":{"rendered":"Signa acord col\u00b7laboraci\u00f3 amb el Servei Jesu\u00efta a Migrants"},"content":{"rendered":"<p>El 16 de juny de 2022 va tenir lloc la signatura de l&#039;acord de col\u00b7laboraci\u00f3 de la <strong>Fundaci\u00f3 per la Just\u00edcia<\/strong> amb el <strong>Servei Jesu\u00efta a Migrants Val\u00e8ncia (SJM).<\/strong> Aquest conveni t\u00e9 com a objectiu la col\u00b7laboraci\u00f3 de les dues entitats en el marc de la<strong> defensa i promoci\u00f3 de drets humans<\/strong>, especialment de la<strong> poblaci\u00f3 migrant en el proc\u00e9s d&#039;integraci\u00f3<\/strong> a la societat d&#039;acollida. Amb aquesta finalitat, es posaran en marxa accions conjuntes que es basaran, entre altres coses, en l&#039;aportaci\u00f3 mutu de recursos humans, locals, recursos de difusi\u00f3 o la cerca conjunta de suport financer o t\u00e8cnic de terceres organitzacions necess\u00e0ries per a la realitzaci\u00f3 de projectes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6279\" src=\"https:\/\/fundacionporlajusticia.org\/wp-content\/uploads\/2022\/06\/IMG_5132.jpg\" alt=\"\" width=\"2016\" height=\"1512\" srcset=\"https:\/\/fundacionporlajusticia.org\/wp-content\/uploads\/2022\/06\/IMG_5132.jpg 2016w, https:\/\/fundacionporlajusticia.org\/wp-content\/uploads\/2022\/06\/IMG_5132-1280x960.jpg 1280w, https:\/\/fundacionporlajusticia.org\/wp-content\/uploads\/2022\/06\/IMG_5132-980x735.jpg 980w, https:\/\/fundacionporlajusticia.org\/wp-content\/uploads\/2022\/06\/IMG_5132-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2016px, 100vw\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>El 16 de junio de 2022 tuvo lugar la firma del acuerdo de colaboraci\u00f3n de la Fundaci\u00f3n por la Justicia con el Servicio Jesuita a Migrantes Valencia (SJM). Este convenio tiene como objetivo la colaboraci\u00f3n de ambas entidades en el marco de la defensa y promoci\u00f3n de derechos humanos, especialmente de la poblaci\u00f3n migrante en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6279,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6,8,1],"tags":[],"class_list":["post-6277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accion-social","category-cooperacion","category-fundacion-por-la-justicia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El 16 de junio de 2022 tuvo lugar la firma del acuerdo de colaboraci\u00f3n de la Fundaci\u00f3n por la Justicia con el Servicio Jesuita a Migrantes Valencia (SJM). Este convenio tiene como objetivo la colaboraci\u00f3n de ambas entidades en el marco de la defensa y promoci\u00f3n de derechos humanos, especialmente de la poblaci\u00f3n migrante en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Comunicaci\u00f3n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"ca_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Fundacion por la justicia - Queremos la Paz, trabajamos por la Justicia\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes - Fundacion por la justicia\" \/>\n\t\t<meta property=\"og:description\" content=\"El 16 de junio de 2022 tuvo lugar la firma del acuerdo de colaboraci\u00f3n de la Fundaci\u00f3n por la Justicia con el Servicio Jesuita a Migrantes Valencia (SJM). Este convenio tiene como objetivo la colaboraci\u00f3n de ambas entidades en el marco de la defensa y promoci\u00f3n de derechos humanos, especialmente de la poblaci\u00f3n migrante en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-06-17T07:45:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-06-17T08:04:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes - Fundacion por la justicia\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El 16 de junio de 2022 tuvo lugar la firma del acuerdo de colaboraci\u00f3n de la Fundaci\u00f3n por la Justicia con el Servicio Jesuita a Migrantes Valencia (SJM). Este convenio tiene como objetivo la colaboraci\u00f3n de ambas entidades en el marco de la defensa y promoci\u00f3n de derechos humanos, especialmente de la poblaci\u00f3n migrante en\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#blogposting\",\"name\":\"Firma acuerdo colaboraci\\u00f3n con el Servicio Jesuita a Migrantes - Fundacion por la justicia\",\"headline\":\"Firma acuerdo colaboraci\\u00f3n con el Servicio Jesuita a Migrantes\",\"author\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/author\\\/comunicacionfundacionporlajusticia-org\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_5132.jpg\",\"width\":2016,\"height\":1512},\"datePublished\":\"2022-06-17T07:45:59+02:00\",\"dateModified\":\"2022-06-17T08:04:26+02:00\",\"inLanguage\":\"ca\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#webpage\"},\"articleSection\":\"Acci\\u00f3n social, Cooperaci\\u00f3n, Fundaci\\u00f3n por la Justicia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/category\\\/fundacion-por-la-justicia\\\/#listItem\",\"name\":\"Fundaci\\u00f3n por la Justicia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/category\\\/fundacion-por-la-justicia\\\/#listItem\",\"position\":2,\"name\":\"Fundaci\\u00f3n por la Justicia\",\"item\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/category\\\/fundacion-por-la-justicia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#listItem\",\"name\":\"Firma acuerdo colaboraci\\u00f3n con el Servicio Jesuita a Migrantes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#listItem\",\"position\":3,\"name\":\"Firma acuerdo colaboraci\\u00f3n con el Servicio Jesuita a Migrantes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/category\\\/fundacion-por-la-justicia\\\/#listItem\",\"name\":\"Fundaci\\u00f3n por la Justicia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/#organization\",\"name\":\"Fundacion por la justicia\",\"description\":\"Queremos la Paz, trabajamos por la Justicia\",\"url\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/author\\\/comunicacionfundacionporlajusticia-org\\\/#author\",\"url\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/author\\\/comunicacionfundacionporlajusticia-org\\\/\",\"name\":\"Comunicaci\\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2951d759044a81d202b5f894215ef8caf553bc027f3fead26439b47c4bc3c1c5?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Comunicaci\\u00f3n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#webpage\",\"url\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/\",\"name\":\"Firma acuerdo colaboraci\\u00f3n con el Servicio Jesuita a Migrantes - Fundacion por la justicia\",\"description\":\"El 16 de junio de 2022 tuvo lugar la firma del acuerdo de colaboraci\\u00f3n de la Fundaci\\u00f3n por la Justicia con el Servicio Jesuita a Migrantes Valencia (SJM). Este convenio tiene como objetivo la colaboraci\\u00f3n de ambas entidades en el marco de la defensa y promoci\\u00f3n de derechos humanos, especialmente de la poblaci\\u00f3n migrante en\",\"inLanguage\":\"ca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/author\\\/comunicacionfundacionporlajusticia-org\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/author\\\/comunicacionfundacionporlajusticia-org\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_5132.jpg\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#mainImage\",\"width\":2016,\"height\":1512},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/firma-convenio-fxj-sjm\\\/#mainImage\"},\"datePublished\":\"2022-06-17T07:45:59+02:00\",\"dateModified\":\"2022-06-17T08:04:26+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/#website\",\"url\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/\",\"name\":\"Fundacion por la justicia\",\"description\":\"Queremos la Paz, trabajamos por la Justicia\",\"inLanguage\":\"ca\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionporlajusticia.org\\\/va\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes - Fundacion por la justicia","description":"El 16 de junio de 2022 tuvo lugar la firma del acuerdo de colaboraci\u00f3n de la Fundaci\u00f3n por la Justicia con el Servicio Jesuita a Migrantes Valencia (SJM). Este convenio tiene como objetivo la colaboraci\u00f3n de ambas entidades en el marco de la defensa y promoci\u00f3n de derechos humanos, especialmente de la poblaci\u00f3n migrante en","canonical_url":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#blogposting","name":"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes - Fundacion por la justicia","headline":"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes","author":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/author\/comunicacionfundacionporlajusticia-org\/#author"},"publisher":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/fundacionporlajusticia.org\/wp-content\/uploads\/2022\/06\/IMG_5132.jpg","width":2016,"height":1512},"datePublished":"2022-06-17T07:45:59+02:00","dateModified":"2022-06-17T08:04:26+02:00","inLanguage":"ca","mainEntityOfPage":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#webpage"},"isPartOf":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#webpage"},"articleSection":"Acci\u00f3n social, Cooperaci\u00f3n, Fundaci\u00f3n por la Justicia"},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/fundacionporlajusticia.org\/va#listItem","position":1,"name":"Home","item":"https:\/\/fundacionporlajusticia.org\/va","nextItem":{"@type":"ListItem","@id":"https:\/\/fundacionporlajusticia.org\/va\/category\/fundacion-por-la-justicia\/#listItem","name":"Fundaci\u00f3n por la Justicia"}},{"@type":"ListItem","@id":"https:\/\/fundacionporlajusticia.org\/va\/category\/fundacion-por-la-justicia\/#listItem","position":2,"name":"Fundaci\u00f3n por la Justicia","item":"https:\/\/fundacionporlajusticia.org\/va\/category\/fundacion-por-la-justicia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#listItem","name":"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/fundacionporlajusticia.org\/va#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#listItem","position":3,"name":"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes","previousItem":{"@type":"ListItem","@id":"https:\/\/fundacionporlajusticia.org\/va\/category\/fundacion-por-la-justicia\/#listItem","name":"Fundaci\u00f3n por la Justicia"}}]},{"@type":"Organization","@id":"https:\/\/fundacionporlajusticia.org\/va\/#organization","name":"Fundacion por la justicia","description":"Queremos la Paz, trabajamos por la Justicia","url":"https:\/\/fundacionporlajusticia.org\/va\/"},{"@type":"Person","@id":"https:\/\/fundacionporlajusticia.org\/va\/author\/comunicacionfundacionporlajusticia-org\/#author","url":"https:\/\/fundacionporlajusticia.org\/va\/author\/comunicacionfundacionporlajusticia-org\/","name":"Comunicaci\u00f3n","image":{"@type":"ImageObject","@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2951d759044a81d202b5f894215ef8caf553bc027f3fead26439b47c4bc3c1c5?s=96&d=mm&r=g","width":96,"height":96,"caption":"Comunicaci\u00f3n"}},{"@type":"WebPage","@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#webpage","url":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/","name":"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes - Fundacion por la justicia","description":"El 16 de junio de 2022 tuvo lugar la firma del acuerdo de colaboraci\u00f3n de la Fundaci\u00f3n por la Justicia con el Servicio Jesuita a Migrantes Valencia (SJM). Este convenio tiene como objetivo la colaboraci\u00f3n de ambas entidades en el marco de la defensa y promoci\u00f3n de derechos humanos, especialmente de la poblaci\u00f3n migrante en","inLanguage":"ca","isPartOf":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/#website"},"breadcrumb":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#breadcrumblist"},"author":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/author\/comunicacionfundacionporlajusticia-org\/#author"},"creator":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/author\/comunicacionfundacionporlajusticia-org\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/fundacionporlajusticia.org\/wp-content\/uploads\/2022\/06\/IMG_5132.jpg","@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#mainImage","width":2016,"height":1512},"primaryImageOfPage":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/#mainImage"},"datePublished":"2022-06-17T07:45:59+02:00","dateModified":"2022-06-17T08:04:26+02:00"},{"@type":"WebSite","@id":"https:\/\/fundacionporlajusticia.org\/va\/#website","url":"https:\/\/fundacionporlajusticia.org\/va\/","name":"Fundacion por la justicia","description":"Queremos la Paz, trabajamos por la Justicia","inLanguage":"ca","publisher":{"@id":"https:\/\/fundacionporlajusticia.org\/va\/#organization"}}]},"og:locale":"ca_ES","og:site_name":"Fundacion por la justicia - Queremos la Paz, trabajamos por la Justicia","og:type":"article","og:title":"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes - Fundacion por la justicia","og:description":"El 16 de junio de 2022 tuvo lugar la firma del acuerdo de colaboraci\u00f3n de la Fundaci\u00f3n por la Justicia con el Servicio Jesuita a Migrantes Valencia (SJM). Este convenio tiene como objetivo la colaboraci\u00f3n de ambas entidades en el marco de la defensa y promoci\u00f3n de derechos humanos, especialmente de la poblaci\u00f3n migrante en","og:url":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/","article:published_time":"2022-06-17T07:45:59+00:00","article:modified_time":"2022-06-17T08:04:26+00:00","twitter:card":"summary_large_image","twitter:title":"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes - Fundacion por la justicia","twitter:description":"El 16 de junio de 2022 tuvo lugar la firma del acuerdo de colaboraci\u00f3n de la Fundaci\u00f3n por la Justicia con el Servicio Jesuita a Migrantes Valencia (SJM). Este convenio tiene como objetivo la colaboraci\u00f3n de ambas entidades en el marco de la defensa y promoci\u00f3n de derechos humanos, especialmente de la poblaci\u00f3n migrante en"},"aioseo_meta_data":{"post_id":"6277","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-12-30 16:09:27","updated":"2025-12-30 16:09:27","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fundacionporlajusticia.org\/va\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fundacionporlajusticia.org\/va\/category\/fundacion-por-la-justicia\/\" title=\"Fundaci\u00f3n por la Justicia\">Fundaci\u00f3n por la Justicia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFirma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/fundacionporlajusticia.org\/va"},{"label":"Fundaci\u00f3n por la Justicia","link":"https:\/\/fundacionporlajusticia.org\/va\/category\/fundacion-por-la-justicia\/"},{"label":"Firma acuerdo colaboraci\u00f3n con el Servicio Jesuita a Migrantes","link":"https:\/\/fundacionporlajusticia.org\/va\/firma-convenio-fxj-sjm\/"}],"_links":{"self":[{"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/posts\/6277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/comments?post=6277"}],"version-history":[{"count":11,"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/posts\/6277\/revisions"}],"predecessor-version":[{"id":6293,"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/posts\/6277\/revisions\/6293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/media\/6279"}],"wp:attachment":[{"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/media?parent=6277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/categories?post=6277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionporlajusticia.org\/va\/wp-json\/wp\/v2\/tags?post=6277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}